{"id":1987,"date":"2003-12-21T13:33:05","date_gmt":"2003-12-21T16:33:05","guid":{"rendered":"http:\/\/marmota.org\/blog\/porque-tudo-e-perigoso"},"modified":"2003-12-21T13:33:05","modified_gmt":"2003-12-21T16:33:05","slug":"porque-tudo-e-perigoso","status":"publish","type":"post","link":"https:\/\/marmota.org\/blog\/porque-tudo-e-perigoso\/","title":{"rendered":"Porque tudo \u00e9 perigoso&#8230;"},"content":{"rendered":"<p><img decoding=\"async\" src=\"\/blog\/secoes\/alo.gif\" align=\"right\" \/>Os mais antigos visitantes do <b>MMM<\/b> v\u00e3o se lembrar <a href=\"\/blog\/archives\/000172.html\"><b>deste post inesquec\u00edvel, sobre como elaborar coment\u00e1rios inteligentes<\/b><\/a>. Trata-se de uma adapta\u00e7\u00e3o a um artigo do <a href=\"http:\/\/www.sitedoaran.com.br\" target=\"_blank\"><b>Edson Aran<\/b><\/a>, chamado &#8220;Raciocinando com Caetano Veloso&#8221;. Raciocinar com ele pode ser perigoso. Porque tudo \u00e9 perigoso. Mas tudo \u00e9 divino e maravilhoso.<\/p>\n<p>Pois n\u00e3o \u00e9 que o pr\u00f3prio Aran descobriu o m\u00e9todo e deixou seu coment\u00e1rio por l\u00e1? Sensacional!<\/p>\n<p><tt>Achei o coment\u00e1rio muito gostoso, embora ser citado assim acabe sendo perigoso. Porque tudo \u00e9 perigoso. Mas tudo \u00e9 divino e maravilhoso.<\/tt><\/p>\n<p>E ainda tem gente que acha rid\u00edculo <a href=\"\/blog\/archives\/000778.html\" target=\"_blank\"><b>n\u00e3o citar a fonte<\/b><\/a>. N\u00e3o esque\u00e7a: usar uma id\u00e9ia como se fosse sua pode ser perigoso. Porque tudo \u00e9&#8230; Bom, voc\u00ea j\u00e1 sabe.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Os mais antigos visitantes do MMM v\u00e3o se lembrar deste post inesquec\u00edvel, sobre como elaborar coment\u00e1rios inteligentes. Trata-se de uma adapta\u00e7\u00e3o a um artigo do Edson Aran, chamado &#8220;Raciocinando com Caetano Veloso&#8221;. Raciocinar com ele pode ser perigoso. Porque tudo \u00e9 perigoso. Mas tudo \u00e9 divino e maravilhoso. Pois n\u00e3o \u00e9 que o pr\u00f3prio Aran [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-1987","post","type-post","status-publish","format-standard","hentry","category-alo-marmota"],"_links":{"self":[{"href":"https:\/\/marmota.org\/blog\/wp-json\/wp\/v2\/posts\/1987","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/marmota.org\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/marmota.org\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/marmota.org\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/marmota.org\/blog\/wp-json\/wp\/v2\/comments?post=1987"}],"version-history":[{"count":0,"href":"https:\/\/marmota.org\/blog\/wp-json\/wp\/v2\/posts\/1987\/revisions"}],"wp:attachment":[{"href":"https:\/\/marmota.org\/blog\/wp-json\/wp\/v2\/media?parent=1987"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/marmota.org\/blog\/wp-json\/wp\/v2\/categories?post=1987"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/marmota.org\/blog\/wp-json\/wp\/v2\/tags?post=1987"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}